{"id":30999,"date":"2019-08-25T07:50:46","date_gmt":"2019-08-25T05:50:46","guid":{"rendered":"https:\/\/www.fierdetreroutier.com\/fdr\/?p=30999"},"modified":"2019-08-25T07:50:46","modified_gmt":"2019-08-25T05:50:46","slug":"550-nouvelles-photos-scania","status":"publish","type":"post","link":"https:\/\/www.fierdetreroutier.com\/fdr\/550-nouvelles-photos-scania\/","title":{"rendered":"550 nouvelles photos SCANIA"},"content":{"rendered":"<p>J&rsquo;avais pris un peu de retard, et puis vous \u00e9tiez de toutes fa\u00e7ons tous \u00e0 Honolulu et aviez donc autre chose \u00e0 foutre que de mater des photos de camion.<br \/>\nDonc, hier soir j&rsquo;ai pris mon courage de demain, enfin, hier et \u00e0 deux mains, pour publier les quelques 550 photos Scania qui s&rsquo;ennuyaient fermement sur mon disque dur.<\/p>\n<p>La mise \u00e0 jour de la rubrique SCANIA c&rsquo;est l\u00e0 : <a href=\"https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/9\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/9<\/a><\/p>\n<p>Special Thanks to les contributeurs nombreux : Hekel, Douadi, Wim, Mich07, Samu, Cordoba, Dud, Tophe, Ville de Valence, Jason, Blum, Luigi, Nautilus, Pat56, Volvoviking<\/p>\n<p>Et si de votre c\u00f4t\u00e9, vous voulez payer le caf\u00e9, un ptit clic sur les banni\u00e8res FDR !<\/p>\n<p><a href=\"https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31000\" data-permalink=\"https:\/\/www.fierdetreroutier.com\/fdr\/550-nouvelles-photos-scania\/20190824212825-344b953b\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX S570&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1564414667&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.7&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"20190824212825-344b953b\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?fit=525%2C394&amp;ssl=1\" class=\"aligncenter wp-image-31000 size-large\" src=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?resize=525%2C394&#038;ssl=1\" alt=\"\" width=\"525\" height=\"394\" srcset=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/a><\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.fierdetreroutier.com\/fdr\/550-nouvelles-photos-scania\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 320px !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>J&rsquo;avais pris un peu de retard, et puis vous \u00e9tiez de toutes fa\u00e7ons tous \u00e0 Honolulu et aviez donc autre chose \u00e0 foutre que de mater des photos de camion. Donc, hier soir j&rsquo;ai pris mon courage de demain, enfin, hier et \u00e0 deux mains, pour publier les quelques 550 photos Scania qui s&rsquo;ennuyaient fermement &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.fierdetreroutier.com\/fdr\/550-nouvelles-photos-scania\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;550 nouvelles photos SCANIA&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":31000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[193,793,201,1204,1283,200,109,121],"class_list":["post-30999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photos-par-marques","tag-193","tag-793","tag-g","tag-ngr","tag-p","tag-r","tag-scania","tag-streamline"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/08\/20190824212825-344b953b.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8M4ry-83Z","jetpack-related-posts":[{"id":52716,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/scania-p-51-nouvelles-photos-2\/","url_meta":{"origin":30999,"position":0},"title":"Scania P, 51 nouvelles photos","author":"","date":"22\/05\/2024","format":false,"excerpt":"Petite cabine d'accord le Scania P, mais Scania quand m\u00eame ! Et il y en a m\u00eame qui dorment dedans ! 51 nouvelles photos \u00e0 retrouver sur votre galerie pr\u00e9f\u00e9r\u00e9e et rang\u00e9es avec soin suivant les normes TUV allemandes en d\u00e9tail ici : https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/recent_cats ou si vous \u00eates pris par\u2026","rel":"","context":"Dans &quot;2024&quot;","block_context":{"text":"2024","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2024\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/05\/IMG_6567.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/05\/IMG_6567.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/05\/IMG_6567.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/05\/IMG_6567.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23688,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/400-nouvelles-photos-scania-avril-2019\/","url_meta":{"origin":30999,"position":1},"title":"400 Nouvelles photos SCANIA avril 2019","author":"","date":"14\/04\/2019","format":false,"excerpt":"Pour survivre, l'homme doit en moyenne absorber 2350 calories, pour entretenir son corps et son cerveau, \u00e0 cel\u00e0, il faut ajouter une quantit\u00e9 minimum d'eau 1,5L, 80% des hommes consomment \u00e9galement au moins une fois dans la semaine du porno sur internet, ce qui est vital pour eux.\u00a0 Il est\u2026","rel":"","context":"Dans &quot;2019&quot;","block_context":{"text":"2019","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2019\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/04\/samu88-3.jpg?fit=1024%2C714&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/04\/samu88-3.jpg?fit=1024%2C714&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/04\/samu88-3.jpg?fit=1024%2C714&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/04\/samu88-3.jpg?fit=1024%2C714&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25546,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/457-nouvelles-photos-scania-juin-2019\/","url_meta":{"origin":30999,"position":2},"title":"457 nouvelles photos Scania, juin 2019","author":"","date":"01\/06\/2019","format":false,"excerpt":"Pas de chance, vous faites parti du 1% de terrien qui n'est pas parti en long week-end de l'Ascension, vous vous sentez nul, seul, mais voil\u00e0, il y a FDR. Et oui, avec cette mise \u00e0 jour de ce d\u00e9but juin de la c\u00e9l\u00e8bre marque su\u00e9doise, au m\u00eame titre que\u2026","rel":"","context":"Dans &quot;2019&quot;","block_context":{"text":"2019","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2019\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/mich07-27.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/mich07-27.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/mich07-27.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/mich07-27.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54646,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/scania-r-76-nouvelles-photos\/","url_meta":{"origin":30999,"position":3},"title":"Scania R, 76 nouvelles photos","author":"","date":"20\/11\/2024","format":false,"excerpt":"Et si on se faisait un petit caprice avec une mise \u00e0 jour de SCANIA R !? Y avait un bail, je suis certain que \u00e7a vous manquait ! Alors en voici 76 toutes nouvelles et quelques collectors sinon, c'est pas dr\u00f4le \u00e0 d\u00e9couvrir ici : https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/scania-serie-r Toutes ces photos\u2026","rel":"","context":"Dans &quot;2024&quot;","block_context":{"text":"2024","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2024\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/11\/20241017_135255.jpg?fit=1024%2C461&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/11\/20241017_135255.jpg?fit=1024%2C461&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/11\/20241017_135255.jpg?fit=1024%2C461&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2024\/11\/20241017_135255.jpg?fit=1024%2C461&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45288,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/scania-serie-r-145-nouvelles-photos\/","url_meta":{"origin":30999,"position":4},"title":"Scania s\u00e9rie R : 145 nouvelles photos","author":"","date":"26\/09\/2022","format":false,"excerpt":"Histoire de bien d\u00e9buter la semaine, et rien que pour vous, voici une mise \u00e0 jour Scania R. Dans 20 ans, il aura toujours ses fans, ne soyez pas les derniers \u00e0 d\u00e9couvrir les photos en cliquant ici : https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/43 Merci \u00e0 eux qui ont commis ces photos et ont\u2026","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/09\/IMG_2706.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/09\/IMG_2706.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/09\/IMG_2706.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/09\/IMG_2706.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49648,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/scania-serie-r-148-nouvelles-photos\/","url_meta":{"origin":30999,"position":5},"title":"Scania s\u00e9rie R, 148 nouvelles photos","author":"","date":"03\/09\/2023","format":false,"excerpt":"Les vacances sont finies, les imp\u00f4ts vous guettent, demain c'est retour \u00e0 la routine, bref vous avez le moral au ras des paquerettes. Alors pour entamer ce mois de juin du bon pied, voici, excusez du peu, 148 nouvelles photos, dont un bon nombre de 2005, donc du temps ou\u2026","rel":"","context":"Dans &quot;2023&quot;","block_context":{"text":"2023","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2023\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/09\/Carlos080223-215.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/09\/Carlos080223-215.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/09\/Carlos080223-215.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/09\/Carlos080223-215.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/30999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/comments?post=30999"}],"version-history":[{"count":1,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/30999\/revisions"}],"predecessor-version":[{"id":31004,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/30999\/revisions\/31004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media\/31000"}],"wp:attachment":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media?parent=30999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/categories?post=30999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/tags?post=30999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}