{"id":44286,"date":"2022-06-18T05:15:15","date_gmt":"2022-06-18T03:15:15","guid":{"rendered":"https:\/\/www.fierdetreroutier.com\/fdr\/?p=44286"},"modified":"2022-06-18T05:15:15","modified_gmt":"2022-06-18T03:15:15","slug":"douai-2022","status":"publish","type":"post","link":"https:\/\/www.fierdetreroutier.com\/fdr\/douai-2022\/","title":{"rendered":"Douai 2022"},"content":{"rendered":"<p>Du lourd, du tr\u00e8s lourd \u00e0 Douai !<\/p>\n<p>Organis\u00e9e au profit des orphelins du transport, la 8e expo a eu lieu \u00e0 Gayant Expo Concerts Douai les 11 et 12 juin 2022 Une expo de qualit\u00e9, une bonne ambiance, amiti\u00e9 et g\u00e9nerosit\u00e9 au progamme. 119 photos sign\u00e9es JP De Bellis<\/p>\n<p><a href=\"https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/5464\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/5464<\/a><\/p>\n<p><a href=\"https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/5464\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"44285\" data-permalink=\"https:\/\/www.fierdetreroutier.com\/fdr\/douai-2022\/img20220612111008\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?fit=1024%2C737&amp;ssl=1\" data-orig-size=\"1024,737\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;OPPO Find X3 Lite 5G&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1655032208&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;1.66&quot;,&quot;iso&quot;:&quot;588&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG20220612111008\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?fit=525%2C378&amp;ssl=1\" class=\"aligncenter wp-image-44285 size-full\" src=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?resize=525%2C378&#038;ssl=1\" alt=\"\" width=\"525\" height=\"378\" srcset=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?resize=300%2C216&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?resize=768%2C553&amp;ssl=1 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.fierdetreroutier.com\/fdr\/douai-2022\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 320px !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Du lourd, du tr\u00e8s lourd \u00e0 Douai ! Organis\u00e9e au profit des orphelins du transport, la 8e expo a eu lieu \u00e0 Gayant Expo Concerts Douai les 11 et 12 juin 2022 Une expo de qualit\u00e9, une bonne ambiance, amiti\u00e9 et g\u00e9nerosit\u00e9 au progamme. 119 photos sign\u00e9es JP De Bellis https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/5464<\/p>\n","protected":false},"author":7,"featured_media":44285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2732,17],"tags":[775],"class_list":["post-44286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2732","category-expos","tag-douai"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/06\/IMG20220612111008.jpg?fit=1024%2C737&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8M4ry-bwi","jetpack-related-posts":[{"id":26070,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/douai-2019\/","url_meta":{"origin":44286,"position":0},"title":"Douai 2019","author":"","date":"21\/06\/2019","format":false,"excerpt":"2019 sera encore un bon cru. Alain et son \u00e9quipe se sont d\u00e9men\u00e9s comme des diables pour v\u00e9hiculer une bonne image de notre m\u00e9tier et pour une tr\u00e8s tr\u00e8s bonne cause ! Photos de JP74 Cliquez-ici : http:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/1322","rel":"","context":"Dans &quot;Expos&quot;","block_context":{"text":"Expos","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/expos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/IMG_20190616_105315.jpg?fit=768%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/IMG_20190616_105315.jpg?fit=768%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/IMG_20190616_105315.jpg?fit=768%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/06\/IMG_20190616_105315.jpg?fit=768%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10486,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/douai-2018\/","url_meta":{"origin":44286,"position":1},"title":"Douai 2018","author":"","date":"19\/06\/2018","format":false,"excerpt":"Vous n'avez p\u00fb vous rendre \u00e0 l'expo de Douai cette ann\u00e9e, c'est pas grave, JP74 nous a ramen\u00e9 quelques photos, merci \u00e0 lui ! Cliquez-ici !!","rel":"","context":"Dans &quot;2018&quot;","block_context":{"text":"2018","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2018\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/06\/Douai-26.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/06\/Douai-26.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/06\/Douai-26.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/06\/Douai-26.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":21583,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/convoi-destination-gb\/","url_meta":{"origin":44286,"position":2},"title":"Convoi destination GB","author":"","date":"20\/03\/2019","format":false,"excerpt":"En convoi, on en profite pour visiter la FRANCE et ses petites routes, jolis paysages et bons restos. Mon itin\u00e9raire est le suivant : VALENCE, VOREPPE, BOURG EN BRESSE, PONT DE VAUX, CHALON SUR SAONE, SEMUR EN AUXOIS, AVALLON, CHABLIS, AUXERRE, SENS, BRAY SUR SEINE, MEAUX, SENLIS, ROUEN, MONDIDIER, ALBERT,\u2026","rel":"","context":"Dans &quot;Un tour avec...&quot;","block_context":{"text":"Un tour avec...","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/un-tour-avec\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/03\/1-21-5.jpg?fit=1028%2C772&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/03\/1-21-5.jpg?fit=1028%2C772&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/03\/1-21-5.jpg?fit=1028%2C772&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2019\/03\/1-21-5.jpg?fit=1028%2C772&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":14448,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/nordic-trophy-2018\/","url_meta":{"origin":44286,"position":3},"title":"Nordic Trophy 2018","author":"","date":"27\/10\/2018","format":false,"excerpt":"Il y a expo et expo... Hekel67 nous a fait parvenir les photos du 39e Nordic Trophy qui s'est d\u00e9roul\u00e9 fin aout, et franchement, il y a du lourd, tr\u00e8s lourd ! On peut \u00eatre un peu surpris par certains attelages, mais il y a sur chacun d'entre eux, un\u2026","rel":"","context":"Dans &quot;2018&quot;","block_context":{"text":"2018","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2018\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/10\/200.jpg?fit=844%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/10\/200.jpg?fit=844%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/10\/200.jpg?fit=844%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2018\/10\/200.jpg?fit=844%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":49282,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/les-transports-ducourneau\/","url_meta":{"origin":44286,"position":4},"title":"Les Transports Ducourneau","author":"","date":"14\/08\/2023","format":false,"excerpt":"91 photos https:\/\/www.fierdetreroutier.fr\/piwigo\/index.php?\/category\/ducourneau Toulounais d'origine, Jean-Pierre Ducourneau est electricien sur les chantiers navals \u00e0 La Seyne sur Mer. En 1971, il d\u00e9panne un ami alors souffrant, et le remplace au volant de son Mercedes 608. D\u00e8s lors, il enchaine les allers retours \u00e0 Paris. Fort de son exp\u00e9rience, il rach\u00e8te\u2026","rel":"","context":"Dans &quot;2023&quot;","block_context":{"text":"2023","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2023\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/08\/Doucourneau.jpg?fit=512%2C360&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":40138,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/wornitz-2003-une-superbe-expo-de-camions-anciens\/","url_meta":{"origin":44286,"position":5},"title":"Wornitz 2003 une superbe expo de camions anciens","author":"","date":"06\/06\/2021","format":false,"excerpt":"Fin aout 2003, s'est d\u00e9roul\u00e9 \u00e0 deux pas de l'Autohof W\u00f6rnitz un magnifique rassemblement de camions anciens, superbement restaur\u00e9s avec des pi\u00e8ces rares et tr\u00e8s peu connues chez nous. Vous d\u00e9couvrirez ici, 132 photos scann\u00e9es par Uwe, un fid\u00e8le et prolifique passionn\u00e9 de camions ! Prenez le temps de cliquer\u2026","rel":"","context":"Dans &quot;2021&quot;","block_context":{"text":"2021","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2021\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/06\/Hanomag-Henschel-F-201.jpg?fit=1024%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/06\/Hanomag-Henschel-F-201.jpg?fit=1024%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/06\/Hanomag-Henschel-F-201.jpg?fit=1024%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/06\/Hanomag-Henschel-F-201.jpg?fit=1024%2C674&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/44286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/comments?post=44286"}],"version-history":[{"count":1,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/44286\/revisions"}],"predecessor-version":[{"id":44290,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/44286\/revisions\/44290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media\/44285"}],"wp:attachment":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media?parent=44286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/categories?post=44286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/tags?post=44286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}