{"id":45909,"date":"2022-11-19T14:15:39","date_gmt":"2022-11-19T13:15:39","guid":{"rendered":"https:\/\/www.fierdetreroutier.com\/fdr\/?p=45909"},"modified":"2022-11-19T14:15:39","modified_gmt":"2022-11-19T13:15:39","slug":"carnet-de-bord-2022-thomas26-semaine-46","status":"publish","type":"post","link":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-thomas26-semaine-46\/","title":{"rendered":"Carnet de bord 2022 &#8211; Thomas26 &#8211; Semaine 46"},"content":{"rendered":"<p><span style=\"font-size: 10pt;\">Il est de retour apr\u00e8s des semaines d&rsquo;absence de publication, mais il a un mot d&rsquo;excuse.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Il n&rsquo;a rien perdu de son verbe, ni de ses plans gal\u00e8re avec son porte chars !!!<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Ne manquez pas le retour de Thomas ici : <a href=\"https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49<\/a><\/span><\/p>\n<figure style=\"width: 800px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full\" src=\"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-11-16.me3.jpg?resize=525%2C394&#038;ssl=1\" alt=\"Volvo FH4b 6x4 Transports Duarig\" width=\"525\" height=\"394\" \/><\/a><figcaption class=\"wp-caption-text\">Volvo FH4b 6&#215;4 Transports Duarig<\/figcaption><\/figure>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-thomas26-semaine-46\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 320px !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>Il est de retour apr\u00e8s des semaines d&rsquo;absence de publication, mais il a un mot d&rsquo;excuse. Il n&rsquo;a rien perdu de son verbe, ni de ses plans gal\u00e8re avec son porte chars !!! Ne manquez pas le retour de Thomas ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2732,112,1864,2684],"tags":[1002,400,838,772],"class_list":["post-45909","post","type-post","status-publish","format-standard","hentry","category-2732","category-carnet-de-bord","category-duarig","category-thomas26","tag-convoi-exceptionnel","tag-paris","tag-porte-chars","tag-rhone-alpes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8M4ry-bWt","jetpack-related-posts":[{"id":46210,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-thomas26-semaine-49\/","url_meta":{"origin":45909,"position":0},"title":"Carnet de bord 2022 &#8211; Thomas26 &#8211; Semaine 49","author":"","date":"11\/12\/2022","format":false,"excerpt":"Il aura support\u00e9 son anorak cette semaine notre Thomas national ! Une semaine men\u00e9e tambour battant ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"Volvo FH4B, Transports Duarig, Rumilly","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-09.Ve3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-09.Ve3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-09.Ve3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-09.Ve3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":46281,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-thomas26-semaine-51\/","url_meta":{"origin":45909,"position":1},"title":"Carnet de bord 2022 &#8211; Thomas26 &#8211; Semaine 51","author":"","date":"24\/12\/2022","format":false,"excerpt":"Il a eu bobo \u00e0 son ventre, bobo a sa t\u00eate, mais il a fait ses 2 tours de Paris comme tout le monde ! Voil\u00e0 un gar\u00e7on serieux qui n'est pas responsable du trou de la s\u00e9cu ! Il nous raconte sa semaine 51 sans prise de t\u00eate mais\u2026","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"Volvo FH4b, transports Duarig, Vincennes","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-19.Lu.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-19.Lu.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-19.Lu.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/49\/orig\/H.2022-12-19.Lu.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":42304,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2021-thomas26-semaine-46\/","url_meta":{"origin":45909,"position":2},"title":"Carnet de bord 2021 &#8211; Thomas26 &#8211; Semaine 46","author":"","date":"21\/11\/2021","format":false,"excerpt":"On ne s'ennuie jamais avec Thomas26, et lui non plus d'ailleurs ! D\u00e8s l'instant qu'il a pris son cacao, il envoie de la buchette, tracteurs, camions anciens, pelleteuses, rien ne l'arr\u00eate ! C'est \u00e0 lire ici dans la joie et la bonne humeur : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49","rel":"","context":"Dans &quot;2021&quot;","block_context":{"text":"2021","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2021\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/11\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/11\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/11\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/11\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42546,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2021-thomas26-semaine-49\/","url_meta":{"origin":45909,"position":3},"title":"Carnet de bord 2021 &#8211; Thomas26  &#8211; Semaine 49","author":"","date":"12\/12\/2021","format":false,"excerpt":"Il est jeune, il est beau, il \u00e9crit comme il parle, et il nous fait toujours rire ! Cette semaine, il aura cumul\u00e9 les petites emmerdes qui mises bout \u00e0 bout finissent pas faire.... Une remorque neuve ! Une semaine cahotique avec plein de rebondissements \u00e0 d\u00e9guster sans mod\u00e9ration ici\u2026","rel":"","context":"Dans &quot;2021&quot;","block_context":{"text":"2021","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2021\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42992,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-thomas26-semaine-2\/","url_meta":{"origin":45909,"position":4},"title":"Carnet de bord 2022 &#8211; Thomas26 &#8211; Semaine 2","author":"","date":"16\/01\/2022","format":false,"excerpt":"Une semaine de reprise post reveillon, post Covid pour Thomas26 ! Il en aura bien bav\u00e9 pour cette remise en jambe, dans le bain direct ! Du Paris, du Grenoble, du Marseille ! Le trio gagnant !!! On embarque \u00e0 bord du R450 ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/01\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/01\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/01\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2022\/01\/Thomas26-1.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42620,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2021-thomas26-semaine-51\/","url_meta":{"origin":45909,"position":5},"title":"Carnet de bord 2021 &#8211; Thomas26 &#8211; Semaine 51","author":"","date":"25\/12\/2021","format":false,"excerpt":"Quoi de mieux pour faire glisser la b\u00fbche qu'une bonne tranche de rigolade ? Avec Thomas26 aux manettes de son Scania, pour des livraisons et chargements plus qu'improbables ! Une excellente conclusion pour cette semaine 51 \u00e0 ne pas manquer ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=49","rel":"","context":"Dans &quot;2021&quot;","block_context":{"text":"2021","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2021\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-3.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-3.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-3.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2021\/12\/Thomas26-3.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/45909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/comments?post=45909"}],"version-history":[{"count":1,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/45909\/revisions"}],"predecessor-version":[{"id":45913,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/45909\/revisions\/45913"}],"wp:attachment":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media?parent=45909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/categories?post=45909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/tags?post=45909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}