{"id":46931,"date":"2023-02-12T16:59:11","date_gmt":"2023-02-12T15:59:11","guid":{"rendered":"https:\/\/www.fierdetreroutier.com\/fdr\/?p=46931"},"modified":"2023-02-12T16:59:11","modified_gmt":"2023-02-12T15:59:11","slug":"carnet-de-bord-2023-bertrand-semaine-6","status":"publish","type":"post","link":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2023-bertrand-semaine-6\/","title":{"rendered":"Carnet de bord 2023 &#8211; Bertrand &#8211; Semaine 6"},"content":{"rendered":"<p>C&rsquo;est que \u00e7a galope pour les Coquellemens, une semaine avec un week-end en Espagne \u00e0 la clef ! Du bouot sans stress pour Bertrand et son fond mouvant : <\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=48\" width=\"800\" height=\"800\"><\/iframe><\/p>\n<div class=\"fb-background-color\">\n\t\t\t  <div \n\t\t\t  \tclass = \"fb-comments\" \n\t\t\t  \tdata-href = \"http:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2023-bertrand-semaine-6\/\"\n\t\t\t  \tdata-numposts = \"10\"\n\t\t\t  \tdata-lazy = \"true\"\n\t\t\t\tdata-colorscheme = \"light\"\n\t\t\t\tdata-order-by = \"social\"\n\t\t\t\tdata-mobile=true>\n\t\t\t  <\/div><\/div>\n\t\t  <style>\n\t\t    .fb-background-color {\n\t\t\t\tbackground: #ffffff !important;\n\t\t\t}\n\t\t\t.fb_iframe_widget_fluid_desktop iframe {\n\t\t\t    width: 320px !important;\n\t\t\t}\n\t\t  <\/style>\n\t\t  ","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est que \u00e7a galope pour les Coquellemens, une semaine avec un week-end en Espagne \u00e0 la clef ! Du bouot sans stress pour Bertrand et son fond mouvant :<\/p>\n","protected":false},"author":7,"featured_media":46932,"comment_status":"open","ping_status":"closed","sticky":false,"template":"template-page-builder.php","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4643,2648,112],"tags":[2680,244,4541,274],"class_list":["post-46931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4643","category-bertrand","category-carnet-de-bord","tag-coquelle","tag-espagne","tag-fond-mouvant","tag-italie"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/bertrand.jpg?fit=539%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8M4ry-ccX","jetpack-related-posts":[{"id":46252,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-bertrand-semaine-50\/","url_meta":{"origin":46931,"position":0},"title":"Carnet de bord 2022 &#8211; Bertrand &#8211; Semaine 50","author":"","date":"18\/12\/2022","format":false,"excerpt":"Une semaine bien frisquette pour Bertrand et son fond mouvant qui l'a amen\u00e9 jusqu'en Allemagne !\u00a0 Gardez vos bonnets et cliquez l\u00e0 : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=48","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"Scania R480, Transports Coquelle","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/48\/orig\/H.2022-12-14.2CDEC98E-66FB-438E-80BB-E9464F7C6EC0.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":46462,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2023-bertrand-semaine-1\/","url_meta":{"origin":46931,"position":1},"title":"Carnet de bord 2023 &#8211; Bertrand  &#8211; Semaine 1","author":"","date":"08\/01\/2023","format":false,"excerpt":"Il attaque l'ann\u00e9e par un week-end plant\u00e9 en Italie. Bertrand vous dit tout depuis son R450 et son fond mouvant ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=48&periode=2023-01","rel":"","context":"Dans &quot;2023&quot;","block_context":{"text":"2023","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2023\/"},"img":{"alt_text":"Scania R450, Transports Coquelle, Aoste","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/48\/orig\/V.2023-01-07.15E73472-6534-4F10-849F-F7116C15C25F.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":46901,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2023-caroto-semaine-6\/","url_meta":{"origin":46931,"position":2},"title":"Carnet de bord 2023 &#8211; Caroto &#8211; Semaine 6","author":"","date":"12\/02\/2023","format":false,"excerpt":"Une belle boucle Italie Paris Provence pour la feignasse du fond mouvant ! \u00e7a d\u00e9marre t\u00f4t le matin, avec les yeux en face des trous... \ufeff","rel":"","context":"Dans &quot;2023&quot;","block_context":{"text":"2023","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2023\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb-1.jpg?fit=1000%2C751&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb-1.jpg?fit=1000%2C751&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb-1.jpg?fit=1000%2C751&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb-1.jpg?fit=1000%2C751&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46827,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2023-caroto-semaine-5\/","url_meta":{"origin":46931,"position":3},"title":"Carnet de bord 2023 &#8211; Caroto &#8211; Semaine 5","author":"","date":"05\/02\/2023","format":false,"excerpt":"Une passionante semaine pour le Y\u00e9ti06, avec une double ration d'Italie : \u00a0","rel":"","context":"Dans &quot;2023&quot;","block_context":{"text":"2023","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2023\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb.jpg?fit=1000%2C751&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb.jpg?fit=1000%2C751&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb.jpg?fit=1000%2C751&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/fdr\/wp-content\/uploads\/2023\/02\/carotocdb.jpg?fit=1000%2C751&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46242,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-baloo-semaine-50\/","url_meta":{"origin":46931,"position":4},"title":"Carnet de bord 2022 &#8211; Baloo &#8211; Semaine 50","author":"","date":"17\/12\/2022","format":false,"excerpt":"En Rh\u00f4ne-Alpes, c'\u00e9tait pas la meilleure semaine niveau m\u00e9t\u00e9o pour faire du r\u00e9gional.\u00a0 Mais notre ami Baloo s'en est pas si mal tir\u00e9 avec son fond mouvant ! Une semaine men\u00e9e tambour battant, retrouvez Baloo et sa friteuse ici :\u00a0 https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=51","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"Renault Range T 460, Transports Coquelle","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/V.2022-12-13.1312-02.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/V.2022-12-13.1312-02.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/V.2022-12-13.1312-02.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":45985,"url":"https:\/\/www.fierdetreroutier.com\/fdr\/carnet-de-bord-2022-baloo-semaine-47\/","url_meta":{"origin":46931,"position":5},"title":"Carnet de bord 2022 &#8211; Baloo &#8211; Semaine 47","author":"","date":"29\/11\/2022","format":false,"excerpt":"Fini la tautliner pour Baloo, changement de cap avec du fond mouvant chez Coquelle. Reprendre ses marques, nouveaux chefs, nouveau boulot, pas simple ! Il est juste pass\u00e9 d'Un Range T \u00e0 un autre ! Il nous raconte tout ici : https:\/\/www.fierdetreroutier.com\/carnet\/index.php?id_chauffeur=51","rel":"","context":"Dans &quot;2022&quot;","block_context":{"text":"2022","link":"https:\/\/www.fierdetreroutier.com\/fdr\/category\/2022\/"},"img":{"alt_text":"Range T460 Coquelle \u00e0 Albens 73","src":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/H.2022-11-23.2311-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/H.2022-11-23.2311-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/H.2022-11-23.2311-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fierdetreroutier.com\/carnet\/photos\/51\/orig\/H.2022-11-23.2311-01.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/46931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/comments?post=46931"}],"version-history":[{"count":1,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/46931\/revisions"}],"predecessor-version":[{"id":46936,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/posts\/46931\/revisions\/46936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media\/46932"}],"wp:attachment":[{"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/media?parent=46931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/categories?post=46931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fierdetreroutier.com\/fdr\/wp-json\/wp\/v2\/tags?post=46931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}